{"id":17040,"date":"2026-04-13T08:20:16","date_gmt":"2026-04-13T08:20:16","guid":{"rendered":"https:\/\/firstbasegroundscrews.com\/?post_type=applications&#038;p=17040"},"modified":"2026-04-14T09:08:15","modified_gmt":"2026-04-14T09:08:15","slug":"strandhaeuser-landal-zeezigt","status":"publish","type":"applications","link":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/","title":{"rendered":"Strandh\u00e4user Landal Zeezigt"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei <a href=\"https:\/\/www.landal.de\/parks\/zeezigt\" type=\"link\" id=\"https:\/\/www.landal.nl\/parken\/zeezigt\">Landal\u00a0Zeezigt<\/a>\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Gemeinsam mit unserem Installationspartner <a href=\"https:\/\/akenschroeffunderingen.nl\/\" type=\"link\" id=\"https:\/\/akenschroeffunderingen.nl\/\"><\/a><a href=\"https:\/\/akenschroeffunderingen.nl\/\" type=\"link\" id=\"https:\/\/akenschroeffunderingen.nl\/\">Van Aken Schroeffunderingen<\/a>\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Da diese Strandh\u00e4user saisonal genutzt werden (April\u2013Oktober), ist das Fundament vollst\u00e4ndig zirkul\u00e4r. Nach der Demontage k\u00f6nnen die Schraubfundamente einfach herausgedreht und beim n\u00e4chsten Projekt wiederverwendet werden.<\/p>\n\n\n\n<div class=\"application-grid\">\n  \n    <div class=\"application-grid__item\" data-col=\"full\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-1620x1080.jpg\" class=\"application-grid__image\" alt=\"Holiday home P\" srcset=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-1620x1080.jpg 1620w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-250x167.jpg 250w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-700x467.jpg 700w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-768x512.jpg 768w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-1536x1024.jpg 1536w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-2048x1365.jpg 2048w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-400x267.jpg 400w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-120x80.jpg 120w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-300x200.jpg 300w\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" \/>\n    <\/div>\n  \n    <div class=\"application-grid__item\" data-col=\"half\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-1620x1080.jpg\" class=\"application-grid__image\" alt=\"Interior Petten beach house\" srcset=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-1620x1080.jpg 1620w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-250x167.jpg 250w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-700x467.jpg 700w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-768x512.jpg 768w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-1536x1024.jpg 1536w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-2048x1365.jpg 2048w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-400x267.jpg 400w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-120x80.jpg 120w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-2-300x200.jpg 300w\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" \/>\n    <\/div>\n  \n    <div class=\"application-grid__item\" data-col=\"half\">\n      <img loading=\"lazy\" decoding=\"async\" width=\"1620\" height=\"1080\" src=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-1620x1080.jpg\" class=\"application-grid__image\" alt=\"Inside the beach house - Petten\" srcset=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-1620x1080.jpg 1620w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-250x167.jpg 250w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-700x467.jpg 700w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-768x512.jpg 768w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-1536x1024.jpg 1536w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-2048x1365.jpg 2048w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-400x267.jpg 400w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-120x80.jpg 120w, https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-3-300x200.jpg 300w\" sizes=\"auto, (max-width: 1620px) 100vw, 1620px\" \/>\n    <\/div>\n  <\/div>","protected":false},"excerpt":{"rendered":"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.\n\nGemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.","protected":false},"featured_media":16746,"menu_order":0,"template":"","tags":[],"field":[7],"class_list":["post-17040","applications","type-applications","status-publish","has-post-thumbnail","hentry","field-pro"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws<\/title>\n<meta name=\"description\" content=\"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws\" \/>\n<meta property=\"og:description\" content=\"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/\" \/>\n<meta property=\"og:site_name\" content=\"FIRST BASE Ground Screws\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-14T09:08:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/\",\"url\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/\",\"name\":\"Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Petten-Landal-1-scaled.jpg\",\"datePublished\":\"2026-04-13T08:20:16+00:00\",\"dateModified\":\"2026-04-14T09:08:15+00:00\",\"description\":\"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Petten-Landal-1-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/Petten-Landal-1-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Holiday home P\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/strandhaeuser-landal-zeezigt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Projects\",\"item\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/projects\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Strandh\u00e4user Landal Zeezigt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/\",\"name\":\"FIRST BASE Ground Screws\",\"description\":\"High quality ground screws for solid foundations\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/firstbasegroundscrews.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws","description":"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/","og_locale":"de_DE","og_type":"article","og_title":"Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws","og_description":"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.","og_url":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/","og_site_name":"FIRST BASE Ground Screws","article_modified_time":"2026-04-14T09:08:15+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/","url":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/","name":"Strandh\u00e4user Landal Zeezigt - FIRST BASE Ground Screws","isPartOf":{"@id":"https:\/\/firstbasegroundscrews.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/#primaryimage"},"image":{"@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/#primaryimage"},"thumbnailUrl":"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-scaled.jpg","datePublished":"2026-04-13T08:20:16+00:00","dateModified":"2026-04-14T09:08:15+00:00","description":"Wir hebben 200 Schraubfundamente in\u00a0Petten\u00a0f\u00fcr die Realisierung von 50 saisonalen Strandh\u00e4usern bei Landal\u00a0Zeezigt\u00a0geliefert. Direkt im Sand, an den D\u00fcnen gebaut; eine Umgebung, in der die Leistungsf\u00e4higkeit des Fundaments entscheidend ist.Gemeinsam mit unserem Installationspartner Van Aken Schroeffunderingen\u00a0wurde das gesamte Fundament in kurzer Zeit realisiert. Durch den Einsatz von \u00d8140 mm verl\u00e4ngerbaren Schraubfundamenten mit L\u00e4ngen zwischen 3,5 und 6 Metern konnten wir maximale Stabilit\u00e4t unter den lokalen Bodenbedingungen erreichen.","breadcrumb":{"@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/#primaryimage","url":"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-scaled.jpg","contentUrl":"https:\/\/firstbasegroundscrews.com\/wp-content\/uploads\/2026\/04\/Petten-Landal-1-scaled.jpg","width":2560,"height":1707,"caption":"Holiday home P"},{"@type":"BreadcrumbList","@id":"https:\/\/firstbasegroundscrews.com\/de\/projects\/strandhaeuser-landal-zeezigt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/firstbasegroundscrews.com\/de\/"},{"@type":"ListItem","position":2,"name":"Projects","item":"https:\/\/firstbasegroundscrews.com\/de\/projects\/"},{"@type":"ListItem","position":3,"name":"Strandh\u00e4user Landal Zeezigt"}]},{"@type":"WebSite","@id":"https:\/\/firstbasegroundscrews.com\/de\/#website","url":"https:\/\/firstbasegroundscrews.com\/de\/","name":"FIRST BASE Ground Screws","description":"High quality ground screws for solid foundations","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/firstbasegroundscrews.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/applications\/17040","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/applications"}],"about":[{"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/types\/applications"}],"version-history":[{"count":4,"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/applications\/17040\/revisions"}],"predecessor-version":[{"id":17340,"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/applications\/17040\/revisions\/17340"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/media\/16746"}],"wp:attachment":[{"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/media?parent=17040"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/tags?post=17040"},{"taxonomy":"field","embeddable":true,"href":"https:\/\/firstbasegroundscrews.com\/de\/wp-json\/wp\/v2\/field?post=17040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}